{"id":55511,"date":"2024-11-11T18:21:01","date_gmt":"2024-11-11T12:51:01","guid":{"rendered":"https:\/\/www.womenfitness.net\/shop\/?post_type=product&#038;p=55511"},"modified":"2024-11-11T18:21:03","modified_gmt":"2024-11-11T12:51:03","slug":"the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts","status":"publish","type":"product","link":"https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/","title":{"rendered":"THE GYM PEOPLE Women&#821..."},"content":{"rendered":"<h3 class=\"product-facts-title\">About this item<\/h3>\n<hr \/>\n<ul class=\"a-unordered-list a-vertical a-spacing-small\">\n<li><span class=\"a-list-item a-size-base a-color-base\">Comfortable &amp; Soft Fabric: The Women&#8217;s Workout Shorts are made of 75%Polyamide, 25%spandex, high-stretch fabric that provides good support and moisture wicking, giving you a comfortable wear experience for summer sports.<\/span><\/li>\n<li><span class=\"a-list-item a-size-base a-color-base\">High Waist &amp; Tummy Control: The Lounge Yoga Shorts designed with a high waist for better tummy control, accentuates your charming waistline and providing extra protection during exercise.<\/span><\/li>\n<li><span class=\"a-list-item a-size-base a-color-base\">Ultra-Short Style: The Ultra-short design is stylish and simple, showing off your curves and visually lengthening your legs, making you look slimmer.<\/span><\/li>\n<li><span class=\"a-list-item a-size-base a-color-base\">Refined Detail: This Lounge shorts designed with white lines wrapping around the sides, back triangular hip line design accentuates the curves of the hips, while side split and curved hem design gives you a sporty look.<\/span><\/li>\n<li><span class=\"a-list-item a-size-base a-color-base\">Occasion: The Workout shorts for women is perfect for summer sports and daily wear, yoga, gym, exercise, fitness, training, basketball, football, workout or lounging.<\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<h3 class=\"a-size-large a-spacing-none a-color-secondary\"><span id=\"productTitle\" class=\"a-size-large product-title-word-break\">THE GYM PEOPLE Women&#8217;s High Waist Workout Shorts Breathable Dolphin Split Elastic Lounge Yoga Shorts<\/span><\/h3>\n<hr \/>\n<p id=\"title\" class=\"a-size-large a-spacing-none a-color-secondary\"><strong>Product details<\/strong><br \/>\nFabric type : 75%Polyamide, 25%spandex<br \/>\nCare instructions : Hand Wash, Tumble Dry Low<br \/>\nOrigin : Imported<br \/>\nClosure type : Pull On<br \/>\nCountry of Origin : China<\/p>\n","protected":false},"featured_media":55512,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"product_cat":[21,16],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>THE GYM PEOPLE Women&#039;s High Waist Workout Shorts Breathable Dolphin Split Elastic Lounge Yoga Shorts - WF Shopping<\/title>\n<meta name=\"description\" content=\"THE GYM PEOPLE Women&#039;s High Waist Workout Shorts Breathable Dolphin Split Elastic Lounge Yoga Shorts, Comfortable &amp; Soft Fabric\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"THE GYM PEOPLE Women&#039;s High Waist Workout Shorts Breathable Dolphin Split Elastic Lounge Yoga Shorts - WF Shopping\" \/>\n<meta property=\"og:description\" content=\"THE GYM PEOPLE Women&#039;s High Waist Workout Shorts Breathable Dolphin Split Elastic Lounge Yoga Shorts, Comfortable &amp; Soft Fabric\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/\" \/>\n<meta property=\"og:site_name\" content=\"WF Shopping\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-11T12:51:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.womenfitness.net\/shop\/wp-content\/uploads\/2024\/11\/THE-GYM-PEOPLE-Womens-High-Waist-Workout-Shorts-Breathable-Dolphin-Split-Elastic-Lounge-Yoga-Shorts.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"522\" \/>\n\t<meta property=\"og:image:height\" content=\"679\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/\",\"url\":\"https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/\",\"name\":\"THE GYM PEOPLE Women's High Waist Workout Shorts Breathable Dolphin Split Elastic Lounge Yoga Shorts - WF Shopping\",\"isPartOf\":{\"@id\":\"https:\/\/www.womenfitness.net\/shop\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.womenfitness.net\/shop\/wp-content\/uploads\/2024\/11\/THE-GYM-PEOPLE-Womens-High-Waist-Workout-Shorts-Breathable-Dolphin-Split-Elastic-Lounge-Yoga-Shorts.jpg\",\"datePublished\":\"2024-11-11T12:51:01+00:00\",\"dateModified\":\"2024-11-11T12:51:03+00:00\",\"description\":\"THE GYM PEOPLE Women's High Waist Workout Shorts Breathable Dolphin Split Elastic Lounge Yoga Shorts, Comfortable & Soft Fabric\",\"breadcrumb\":{\"@id\":\"https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/#primaryimage\",\"url\":\"https:\/\/www.womenfitness.net\/shop\/wp-content\/uploads\/2024\/11\/THE-GYM-PEOPLE-Womens-High-Waist-Workout-Shorts-Breathable-Dolphin-Split-Elastic-Lounge-Yoga-Shorts.jpg\",\"contentUrl\":\"https:\/\/www.womenfitness.net\/shop\/wp-content\/uploads\/2024\/11\/THE-GYM-PEOPLE-Womens-High-Waist-Workout-Shorts-Breathable-Dolphin-Split-Elastic-Lounge-Yoga-Shorts.jpg\",\"width\":522,\"height\":679,\"caption\":\"THE GYM PEOPLE Women's High Waist Workout Shorts Breathable Dolphin Split Elastic Lounge Yoga Shorts\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.womenfitness.net\/shop\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.womenfitness.net\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"THE GYM PEOPLE Women&#821...\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.womenfitness.net\/shop\/#website\",\"url\":\"https:\/\/www.womenfitness.net\/shop\/\",\"name\":\"WF Shopping\",\"description\":\"An exhaustive resource of Women Fitness and Health\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.womenfitness.net\/shop\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"THE GYM PEOPLE Women's High Waist Workout Shorts Breathable Dolphin Split Elastic Lounge Yoga Shorts - WF Shopping","description":"THE GYM PEOPLE Women's High Waist Workout Shorts Breathable Dolphin Split Elastic Lounge Yoga Shorts, Comfortable & Soft Fabric","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/","og_locale":"en_US","og_type":"article","og_title":"THE GYM PEOPLE Women's High Waist Workout Shorts Breathable Dolphin Split Elastic Lounge Yoga Shorts - WF Shopping","og_description":"THE GYM PEOPLE Women's High Waist Workout Shorts Breathable Dolphin Split Elastic Lounge Yoga Shorts, Comfortable & Soft Fabric","og_url":"https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/","og_site_name":"WF Shopping","article_modified_time":"2024-11-11T12:51:03+00:00","og_image":[{"width":522,"height":679,"url":"https:\/\/www.womenfitness.net\/shop\/wp-content\/uploads\/2024\/11\/THE-GYM-PEOPLE-Womens-High-Waist-Workout-Shorts-Breathable-Dolphin-Split-Elastic-Lounge-Yoga-Shorts.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/","url":"https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/","name":"THE GYM PEOPLE Women's High Waist Workout Shorts Breathable Dolphin Split Elastic Lounge Yoga Shorts - WF Shopping","isPartOf":{"@id":"https:\/\/www.womenfitness.net\/shop\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/#primaryimage"},"image":{"@id":"https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/#primaryimage"},"thumbnailUrl":"https:\/\/www.womenfitness.net\/shop\/wp-content\/uploads\/2024\/11\/THE-GYM-PEOPLE-Womens-High-Waist-Workout-Shorts-Breathable-Dolphin-Split-Elastic-Lounge-Yoga-Shorts.jpg","datePublished":"2024-11-11T12:51:01+00:00","dateModified":"2024-11-11T12:51:03+00:00","description":"THE GYM PEOPLE Women's High Waist Workout Shorts Breathable Dolphin Split Elastic Lounge Yoga Shorts, Comfortable & Soft Fabric","breadcrumb":{"@id":"https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/#primaryimage","url":"https:\/\/www.womenfitness.net\/shop\/wp-content\/uploads\/2024\/11\/THE-GYM-PEOPLE-Womens-High-Waist-Workout-Shorts-Breathable-Dolphin-Split-Elastic-Lounge-Yoga-Shorts.jpg","contentUrl":"https:\/\/www.womenfitness.net\/shop\/wp-content\/uploads\/2024\/11\/THE-GYM-PEOPLE-Womens-High-Waist-Workout-Shorts-Breathable-Dolphin-Split-Elastic-Lounge-Yoga-Shorts.jpg","width":522,"height":679,"caption":"THE GYM PEOPLE Women's High Waist Workout Shorts Breathable Dolphin Split Elastic Lounge Yoga Shorts"},{"@type":"BreadcrumbList","@id":"https:\/\/www.womenfitness.net\/shop\/product\/the-gym-people-womens-high-waist-workout-shorts-breathable-dolphin-split-elastic-lounge-yoga-shorts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.womenfitness.net\/shop\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.womenfitness.net\/shop\/"},{"@type":"ListItem","position":3,"name":"THE GYM PEOPLE Women&#821..."}]},{"@type":"WebSite","@id":"https:\/\/www.womenfitness.net\/shop\/#website","url":"https:\/\/www.womenfitness.net\/shop\/","name":"WF Shopping","description":"An exhaustive resource of Women Fitness and Health","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.womenfitness.net\/shop\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.womenfitness.net\/shop\/wp-json\/wp\/v2\/product\/55511"}],"collection":[{"href":"https:\/\/www.womenfitness.net\/shop\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.womenfitness.net\/shop\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.womenfitness.net\/shop\/wp-json\/wp\/v2\/comments?post=55511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.womenfitness.net\/shop\/wp-json\/wp\/v2\/media\/55512"}],"wp:attachment":[{"href":"https:\/\/www.womenfitness.net\/shop\/wp-json\/wp\/v2\/media?parent=55511"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.womenfitness.net\/shop\/wp-json\/wp\/v2\/product_cat?post=55511"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.womenfitness.net\/shop\/wp-json\/wp\/v2\/product_tag?post=55511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}